{"id":54482,"date":"2024-07-28T11:59:31","date_gmt":"2024-07-28T11:59:31","guid":{"rendered":"https:\/\/maisonheavenly.com\/product\/celest-boucle-doreille-gm-5\/"},"modified":"2024-10-16T06:40:21","modified_gmt":"2024-10-16T06:40:21","slug":"celgm24-e3pg-go-go","status":"publish","type":"product","link":"https:\/\/maisonheavenly.com\/fr\/produit\/celgm24-e3pg-go-go\/","title":{"rendered":"CELEST BOUCLE D&#8217;OREILLE GM 2"},"content":{"rendered":"<p>Chics, les boucles d&#8217;oreilles CELEST en or rose, suspendues \u00e0 une tige en or et soulign\u00e9es par un diamant central et une ligne de diamants, expriment la force d&#8217;une union unique.<br \/>\nCette \u00e9vocation est enrichie par la vibration du 3, le nombre du dialogue, signifiant l&#8217;impulsion vers l&#8217;autre.<br \/>\n\u00c9l\u00e9gantes et raffin\u00e9es, ces boucles d&#8217;oreilles peuvent \u00eatre port\u00e9es seules ou en duo pour un look glam-rock.<\/p>\n<p data-pm-slice=\"1 1 []\">Vendu \u00e0 l&#8217;unit\u00e9.<\/p>\n<p>CELGM24.E3PG.GO.GO<\/p>\n<p><b>1 Unit\u00e9<\/b><\/p>\n<p><strong>Pierres: <\/strong>1+16<\/p>\n<p><strong>Poids carat: <\/strong>0,24ct<\/p>\n<p><em>Toutes les cr\u00e9ations de la Maison Heavenly sont enregistr\u00e9es, num\u00e9rot\u00e9es individuellement et uniques : le poids de l\u2019or, le caratage et la taille des pierres peuvent l\u00e9g\u00e8rement varier d\u2019une pi\u00e8ce \u00e0 l\u2019autre.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Or rose recycl\u00e9 750\/1000<br \/>\nDiamants<\/p>\n","protected":false},"featured_media":55862,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[214,194,242,191],"product_tag":[],"class_list":{"0":"post-54482","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-boucles-doreilles","7":"product_cat-celest-boucles-doreilles","8":"product_cat-cadeaux-cosmiques","9":"product_cat-celest-fr","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/maisonheavenly.com\/fr\/wp-json\/wp\/v2\/product\/54482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maisonheavenly.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/maisonheavenly.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/maisonheavenly.com\/fr\/wp-json\/wp\/v2\/comments?post=54482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maisonheavenly.com\/fr\/wp-json\/wp\/v2\/media\/55862"}],"wp:attachment":[{"href":"https:\/\/maisonheavenly.com\/fr\/wp-json\/wp\/v2\/media?parent=54482"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/maisonheavenly.com\/fr\/wp-json\/wp\/v2\/product_brand?post=54482"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/maisonheavenly.com\/fr\/wp-json\/wp\/v2\/product_cat?post=54482"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/maisonheavenly.com\/fr\/wp-json\/wp\/v2\/product_tag?post=54482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}